{"id":2577,"date":"2022-11-09T08:27:20","date_gmt":"2022-11-09T08:27:20","guid":{"rendered":"https:\/\/hexadindustries.com\/hexad-glass\/"},"modified":"2025-07-03T08:13:05","modified_gmt":"2025-07-03T08:13:05","slug":"hexad-glass","status":"publish","type":"page","link":"https:\/\/hexadindustries.com\/de\/","title":{"rendered":"Hexad Glass"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"2577\" class=\"elementor elementor-2577 elementor-13\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3c55427 elementor-section-content-bottom elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3c55427\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2f709b39\" data-id=\"2f709b39\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-634cc92e elementor-widget elementor-widget-heading\" data-id=\"634cc92e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-small\">Alle Geb\u00e4ude Glas Gro\u00dfhandel zum Fabrikpreis<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5640b1d elementor-widget elementor-widget-text-editor\" data-id=\"5640b1d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Sie brauchen mehr als nur ein einziges Glasmaterial, Sie brauchen einen erfahrenen Lieferanten, der seit 12 Jahren in diesem Bereich t\u00e4tig ist, um Ihre Marke aufzubauen und Ihre Gewinne zu steigern; Lassen Sie sich von HEXAD zum gesch\u00e4ftlichen Erfolg verhelfen<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-59c7a424 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"59c7a424\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg elementor-animation-float\" href=\"https:\/\/hexadindustries.com\/de\/anfrage\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Sofortiges Angebot einholen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7d2ef38\" data-id=\"7d2ef38\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7ee408b8 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7ee408b8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-42ea8457\" data-id=\"42ea8457\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7f3d5bb0 elementor-widget elementor-widget-heading\" data-id=\"7f3d5bb0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">All-in-One-L\u00f6sung f\u00fcr Geb\u00e4udeglas<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-13900d6e elementor-widget elementor-widget-heading\" data-id=\"13900d6e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Dank der fortschrittlichen Produktion und der erweiterten Kapazit\u00e4t des gesamten Glasgro\u00dfhandels k\u00f6nnen Sie wirklich Zeit sparen und sich auf Ihr Projekt konzentrieren.<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3c206352 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3c206352\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"make-column-clickable-elementor elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-2434852\" style=\"cursor: pointer;\" data-column-clickable=\"https:\/\/hexadindustries.com\/architectural-glass\/\" data-column-clickable-blank=\"_self\" data-id=\"2434852\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b8a0c5c elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"b8a0c5c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img fetchpriority=\"high\" decoding=\"async\" width=\"490\" height=\"380\" src=\"https:\/\/hexadindustries.com\/wp-content\/uploads\/2022\/11\/Architectural-Galss.jpg\" class=\"attachment-full size-full wp-image-232\" alt=\"\" srcset=\"https:\/\/hexadindustries.com\/wp-content\/uploads\/2022\/11\/Architectural-Galss.jpg 490w, https:\/\/hexadindustries.com\/wp-content\/uploads\/2022\/11\/Architectural-Galss-300x233.jpg 300w\" sizes=\"(max-width: 490px) 100vw, 490px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Architektonisches Glas<\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-bf79054\" data-id=\"bf79054\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-803a4e8 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"803a4e8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"490\" height=\"380\" src=\"https:\/\/hexadindustries.com\/wp-content\/uploads\/2022\/11\/Decorative-Glass.jpg\" class=\"attachment-full size-full wp-image-224\" alt=\"\" srcset=\"https:\/\/hexadindustries.com\/wp-content\/uploads\/2022\/11\/Decorative-Glass.jpg 490w, https:\/\/hexadindustries.com\/wp-content\/uploads\/2022\/11\/Decorative-Glass-300x233.jpg 300w\" sizes=\"(max-width: 490px) 100vw, 490px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Dekoratives Glas<\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"make-column-clickable-elementor elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-6d30f989\" style=\"cursor: pointer;\" data-column-clickable=\"https:\/\/hexadindustries.com\/laminated-glass\/\" data-column-clickable-blank=\"_blank\" data-id=\"6d30f989\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-11c931a6 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"11c931a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/hexadindustries.com\/de\/verbundsicherheitsglas\/\" tabindex=\"-1\"><img decoding=\"async\" width=\"490\" height=\"380\" src=\"https:\/\/hexadindustries.com\/wp-content\/uploads\/2022\/11\/Laminated-Glass.jpg\" class=\"attachment-full size-full wp-image-225\" alt=\"Laminated Glass\" srcset=\"https:\/\/hexadindustries.com\/wp-content\/uploads\/2022\/11\/Laminated-Glass.jpg 490w, https:\/\/hexadindustries.com\/wp-content\/uploads\/2022\/11\/Laminated-Glass-300x233.jpg 300w\" sizes=\"(max-width: 490px) 100vw, 490px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/hexadindustries.com\/de\/verbundsicherheitsglas\/\">Verbundsicherheitsglas<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"make-column-clickable-elementor elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-66324f0\" style=\"cursor: pointer;\" data-column-clickable=\"https:\/\/hexadindustries.com\/mirror-glass-wholesale\/\" data-column-clickable-blank=\"_self\" data-id=\"66324f0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7a65920 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"7a65920\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"490\" height=\"380\" src=\"https:\/\/hexadindustries.com\/wp-content\/uploads\/2022\/11\/Mirror-Glass.jpg\" class=\"attachment-full size-full wp-image-233\" alt=\"\" srcset=\"https:\/\/hexadindustries.com\/wp-content\/uploads\/2022\/11\/Mirror-Glass.jpg 490w, https:\/\/hexadindustries.com\/wp-content\/uploads\/2022\/11\/Mirror-Glass-300x233.jpg 300w\" sizes=\"(max-width: 490px) 100vw, 490px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Spiegelglas<\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-19e4946 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"19e4946\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"make-column-clickable-elementor elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-3b131f6e\" style=\"cursor: pointer;\" data-column-clickable=\"https:\/\/hexadindustries.com\/tempered-glass-manufacturer\/\" data-column-clickable-blank=\"_blank\" data-id=\"3b131f6e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-45fc4b5e elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"45fc4b5e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"490\" height=\"380\" src=\"https:\/\/hexadindustries.com\/wp-content\/uploads\/2022\/11\/Tempered-Glass.jpg\" class=\"attachment-full size-full wp-image-228\" alt=\"Tempered Glass Manufacturer\" srcset=\"https:\/\/hexadindustries.com\/wp-content\/uploads\/2022\/11\/Tempered-Glass.jpg 490w, https:\/\/hexadindustries.com\/wp-content\/uploads\/2022\/11\/Tempered-Glass-300x233.jpg 300w\" sizes=\"(max-width: 490px) 100vw, 490px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Geh\u00e4rtetes Glas<\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-cd2023e\" data-id=\"cd2023e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e03a375 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"e03a375\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"490\" height=\"380\" src=\"https:\/\/hexadindustries.com\/wp-content\/uploads\/2022\/11\/Anti-Reflective-Glass-1.jpg\" class=\"attachment-full size-full wp-image-222\" alt=\"Anti Reflective Glass\" srcset=\"https:\/\/hexadindustries.com\/wp-content\/uploads\/2022\/11\/Anti-Reflective-Glass-1.jpg 490w, https:\/\/hexadindustries.com\/wp-content\/uploads\/2022\/11\/Anti-Reflective-Glass-1-300x233.jpg 300w\" sizes=\"(max-width: 490px) 100vw, 490px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">AG \/ AR Glass<\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"make-column-clickable-elementor elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-c676f81\" style=\"cursor: pointer;\" data-column-clickable=\"https:\/\/hexadindustries.com\/reflective-glass\/\" data-column-clickable-blank=\"_blank\" data-id=\"c676f81\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6c4abdb elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"6c4abdb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"490\" height=\"380\" src=\"https:\/\/hexadindustries.com\/wp-content\/uploads\/2022\/11\/Reflective-Glass-Hexad.jpg\" class=\"attachment-full size-full wp-image-226\" alt=\"Reflective Glass Hexad\" srcset=\"https:\/\/hexadindustries.com\/wp-content\/uploads\/2022\/11\/Reflective-Glass-Hexad.jpg 490w, https:\/\/hexadindustries.com\/wp-content\/uploads\/2022\/11\/Reflective-Glass-Hexad-300x233.jpg 300w\" sizes=\"(max-width: 490px) 100vw, 490px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Reflektierendes Glas<\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"make-column-clickable-elementor elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-bda30d2\" style=\"cursor: pointer;\" data-column-clickable=\"https:\/\/hexadindustries.com\/float-glass\/\" data-column-clickable-blank=\"_blank\" data-id=\"bda30d2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-09c5a0a elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"09c5a0a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/hexadindustries.com\/de\/floatglas\/\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"490\" height=\"380\" src=\"https:\/\/hexadindustries.com\/wp-content\/uploads\/2022\/11\/Clear-Float-Glass.jpg\" class=\"attachment-full size-full wp-image-223\" alt=\"Clear Float Glass\" srcset=\"https:\/\/hexadindustries.com\/wp-content\/uploads\/2022\/11\/Clear-Float-Glass.jpg 490w, https:\/\/hexadindustries.com\/wp-content\/uploads\/2022\/11\/Clear-Float-Glass-300x233.jpg 300w\" sizes=\"(max-width: 490px) 100vw, 490px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/hexadindustries.com\/de\/floatglas\/\">Floatglas<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-81f2e62 elementor-align-center elementor-button-info elementor-widget elementor-widget-button\" data-id=\"81f2e62\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Schnelles Angebot einholen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5585e1d6 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5585e1d6\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-364cf954\" data-id=\"364cf954\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3ee4d2c1 elementor-widget elementor-widget-image\" data-id=\"3ee4d2c1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"590\" height=\"520\" src=\"https:\/\/hexadindustries.com\/wp-content\/uploads\/2022\/11\/Hexad-Industries.jpg\" class=\"attachment-full size-full wp-image-1829\" alt=\"\" srcset=\"https:\/\/hexadindustries.com\/wp-content\/uploads\/2022\/11\/Hexad-Industries.jpg 590w, https:\/\/hexadindustries.com\/wp-content\/uploads\/2022\/11\/Hexad-Industries-300x264.jpg 300w\" sizes=\"(max-width: 590px) 100vw, 590px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-113da908\" data-id=\"113da908\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4de49878 elementor-widget elementor-widget-heading\" data-id=\"4de49878\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Was uns auszeichnet<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6dcd1f06 elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"6dcd1f06\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-industry\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tStarke Kapazit\u00e4t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tEgal, ob es sich um Floatglas oder um tief verarbeitete und gebrauchsfertige Verglasungen handelt, Hexad kann problemlos liefern; Sie k\u00f6nnen von der Dicke bis zur Solarbeschichtung individuell gestalten;\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3658cde9 elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"3658cde9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-thumbs-up\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tZustimmung der Kunden\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tHexad ist seit \u00fcber 2 Jahrzehnten in der Glasindustrie t\u00e4tig und hat Kunden in \u00fcber 70 L\u00e4ndern und Regionen geholfen; Ob gro\u00df oder klein, Ihre Anforderungen k\u00f6nnen schnell und effizient erf\u00fcllt werden\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3ade3628 elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"3ade3628\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chalkboard-teacher\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tSpezialisierte L\u00f6sung\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tMit mehr als 20 Jahren Erfahrung in der Glasindustrie kennt Hexad alle Ihre \u00dcberlegungen zum Glasgro\u00dfhandel; Alles, was Sie bekommen, ist die beste L\u00f6sung.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-77cbb5eb elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"77cbb5eb\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1a70ef35\" data-id=\"1a70ef35\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2a72c9f7 elementor-widget elementor-widget-heading\" data-id=\"2a72c9f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Warum HEXAD w\u00e4hlen?<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9cdb5ab elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"9cdb5ab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-7bbce4e0\" data-id=\"7bbce4e0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-197a3d60 elementor-widget elementor-widget-image\" data-id=\"197a3d60\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"700\" src=\"https:\/\/hexadindustries.com\/wp-content\/uploads\/2022\/11\/Price-Advantage.jpg\" class=\"elementor-animation-grow attachment-full size-full wp-image-1805\" alt=\"\" srcset=\"https:\/\/hexadindustries.com\/wp-content\/uploads\/2022\/11\/Price-Advantage.jpg 600w, https:\/\/hexadindustries.com\/wp-content\/uploads\/2022\/11\/Price-Advantage-257x300.jpg 257w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-31b457c elementor-widget elementor-widget-text-editor\" data-id=\"31b457c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Preisvorteil<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1dff5958 elementor-widget elementor-widget-text-editor\" data-id=\"1dff5958\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>F\u00fcr H\u00e4ndler, kaufen in der Masse kann einen besseren Preis zu bekommen. Sparen Sie Versand- und Einkaufskosten F\u00fcr Einzelh\u00e4ndler und eigene Projekte nehmen wir auch kleine Bestellungen entgegen; Zum Beispiel MOQ 1 St\u00fcck f\u00fcr Glasmalerei panel.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-172738e7\" data-id=\"172738e7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-525b8e9 elementor-widget elementor-widget-text-editor\" data-id=\"525b8e9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Blitzschnelle Lieferung<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3cff4d22 elementor-widget elementor-widget-text-editor\" data-id=\"3cff4d22\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die hohe Produktionskapazit\u00e4t und der schnelle Lagerumschlag sorgen f\u00fcr eine zuverl\u00e4ssige Versorgung Neben den Glasmaterialien finden Sie hier auch die dazugeh\u00f6rigen Installationsprodukte;<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-421505b1 elementor-widget elementor-widget-image\" data-id=\"421505b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"700\" src=\"https:\/\/hexadindustries.com\/wp-content\/uploads\/2022\/11\/Fast-Shipping.jpg\" class=\"elementor-animation-grow attachment-full size-full wp-image-1799\" alt=\"\" srcset=\"https:\/\/hexadindustries.com\/wp-content\/uploads\/2022\/11\/Fast-Shipping.jpg 600w, https:\/\/hexadindustries.com\/wp-content\/uploads\/2022\/11\/Fast-Shipping-257x300.jpg 257w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7bcf9fe9 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7bcf9fe9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6eec84b7\" data-id=\"6eec84b7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-362191bd elementor-widget elementor-widget-heading\" data-id=\"362191bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Was unsere Kunden \u00fcber uns sagen<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7a52fc29 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7a52fc29\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-181c7111\" data-id=\"181c7111\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6661c1c7 elementor-widget elementor-widget-testimonial\" data-id=\"6661c1c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"testimonial.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial-wrapper\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial-content\">HEXAD ist unser bester Partner f\u00fcr Verbundglas und geh\u00e4rtetes Glas, weil er uns durch die Beschaffung von hochwertigem Glas zu einem erschwinglichen Preis und mit unglaublichen Durchlaufzeiten un\u00fcbertroffen hilft; Dar\u00fcber hinaus hat HEXAD uns geholfen, unser gesamtes architektonisches Glasdesign zu verbessern, danke!<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-testimonial-meta elementor-has-image elementor-testimonial-image-position-aside\">\n\t\t\t\t<div class=\"elementor-testimonial-meta-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-image\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/hexadindustries.com\/wp-content\/uploads\/2022\/11\/1.jpg\" class=\"attachment-full size-full wp-image-295\" alt=\"\" srcset=\"https:\/\/hexadindustries.com\/wp-content\/uploads\/2022\/11\/1.jpg 400w, https:\/\/hexadindustries.com\/wp-content\/uploads\/2022\/11\/1-100x100.jpg 100w, https:\/\/hexadindustries.com\/wp-content\/uploads\/2022\/11\/1-300x300.jpg 300w, https:\/\/hexadindustries.com\/wp-content\/uploads\/2022\/11\/1-150x150.jpg 150w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-details\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-name\">Robert Aderson<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-job\">Auftragnehmer, US<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-62343b32\" data-id=\"62343b32\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-311d9d84 elementor-widget elementor-widget-testimonial\" data-id=\"311d9d84\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"testimonial.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial-wrapper\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial-content\">HEXAD, ein langj\u00e4hriger Freund und strategischer Partner, dem wir am meisten vertrauen, verf\u00fcgt \u00fcber eine der besten Glasprodukte und Fertigungstechnologien und beliefert unser Unternehmen stets mit Produkten h\u00f6chster Qualit\u00e4t Die Zusammenarbeit mit HEAD ist gl\u00fccklich und erfolgreich;<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-testimonial-meta elementor-has-image elementor-testimonial-image-position-aside\">\n\t\t\t\t<div class=\"elementor-testimonial-meta-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-image\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/hexadindustries.com\/wp-content\/uploads\/2022\/11\/2.jpg\" class=\"attachment-full size-full wp-image-296\" alt=\"\" srcset=\"https:\/\/hexadindustries.com\/wp-content\/uploads\/2022\/11\/2.jpg 400w, https:\/\/hexadindustries.com\/wp-content\/uploads\/2022\/11\/2-100x100.jpg 100w, https:\/\/hexadindustries.com\/wp-content\/uploads\/2022\/11\/2-300x300.jpg 300w, https:\/\/hexadindustries.com\/wp-content\/uploads\/2022\/11\/2-150x150.jpg 150w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-details\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-name\">Augusto Hernandez<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-job\">Entrepreneur, Kolumbien<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-13433332 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"13433332\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6b3e1379\" data-id=\"6b3e1379\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3f520099 elementor-widget elementor-widget-heading\" data-id=\"3f520099\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Aktuelle Nachrichten &amp; Blogs<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a336fb5 elementor-widget elementor-widget-heading\" data-id=\"a336fb5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">HEXAD ist seit mehr als 20 Jahren im Glasgro\u00dfhandel t\u00e4tig und wir k\u00f6nnen Ihnen helfen, das gesamte Wissen \u00fcber Glas zu verstehen.<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0327d84 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0327d84\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-custom\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-543f708\" data-id=\"543f708\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-df3a981 elementor-widget elementor-widget-image\" data-id=\"df3a981\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"490\" height=\"380\" src=\"https:\/\/hexadindustries.com\/wp-content\/uploads\/2022\/11\/Architectual-Glass-101.jpg\" class=\"attachment-large size-large wp-image-1811\" alt=\"\" srcset=\"https:\/\/hexadindustries.com\/wp-content\/uploads\/2022\/11\/Architectual-Glass-101.jpg 490w, https:\/\/hexadindustries.com\/wp-content\/uploads\/2022\/11\/Architectual-Glass-101-300x233.jpg 300w\" sizes=\"(max-width: 490px) 100vw, 490px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fff124e elementor-widget elementor-widget-heading\" data-id=\"fff124e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Architekturglas 101, Finden Sie die L\u00f6sung aus einer Hand<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-bd82895\" data-id=\"bd82895\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b46681e elementor-widget elementor-widget-image\" data-id=\"b46681e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"490\" height=\"380\" src=\"https:\/\/hexadindustries.com\/wp-content\/uploads\/2022\/11\/Laminated-Glass-vs-Tempered-Glass.jpg\" class=\"attachment-large size-large wp-image-1817\" alt=\"\" srcset=\"https:\/\/hexadindustries.com\/wp-content\/uploads\/2022\/11\/Laminated-Glass-vs-Tempered-Glass.jpg 490w, https:\/\/hexadindustries.com\/wp-content\/uploads\/2022\/11\/Laminated-Glass-vs-Tempered-Glass-300x233.jpg 300w\" sizes=\"(max-width: 490px) 100vw, 490px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ff6d7d7 elementor-widget elementor-widget-heading\" data-id=\"ff6d7d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Was sollte ich w\u00e4hlen: Verbundsicherheitsglas vs. geh\u00e4rtetes Glas?<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-a41f24f\" data-id=\"a41f24f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4038062 elementor-widget elementor-widget-image\" data-id=\"4038062\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"490\" height=\"380\" src=\"https:\/\/hexadindustries.com\/wp-content\/uploads\/2022\/11\/Reflective-Glass-vs-Tinted-Glass.jpg\" class=\"attachment-large size-large wp-image-1823\" alt=\"\" srcset=\"https:\/\/hexadindustries.com\/wp-content\/uploads\/2022\/11\/Reflective-Glass-vs-Tinted-Glass.jpg 490w, https:\/\/hexadindustries.com\/wp-content\/uploads\/2022\/11\/Reflective-Glass-vs-Tinted-Glass-300x233.jpg 300w\" sizes=\"(max-width: 490px) 100vw, 490px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cd384a6 elementor-widget elementor-widget-heading\" data-id=\"cd384a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Was ist Floatglas und welche Vorteile bietet Floatglas?<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"make-column-clickable-elementor elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-85bc50d\" style=\"cursor: pointer;\" data-column-clickable=\"https:\/\/hexadindustries.com\/buying-guide-reflective-glass-vs-tinted-glass\/\" data-column-clickable-blank=\"_self\" data-id=\"85bc50d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bf1c1e2 elementor-widget elementor-widget-image\" data-id=\"bf1c1e2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"490\" height=\"380\" src=\"https:\/\/hexadindustries.com\/wp-content\/uploads\/2022\/11\/Reflective-Glass.jpg\" class=\"attachment-large size-large wp-image-227\" alt=\"Reflective Glass\" srcset=\"https:\/\/hexadindustries.com\/wp-content\/uploads\/2022\/11\/Reflective-Glass.jpg 490w, https:\/\/hexadindustries.com\/wp-content\/uploads\/2022\/11\/Reflective-Glass-300x233.jpg 300w\" sizes=\"(max-width: 490px) 100vw, 490px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5ce0c15 elementor-widget elementor-widget-heading\" data-id=\"5ce0c15\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Einkaufsf\u00fchrer: Reflektierendes Glas vs. get\u00f6ntes Glas<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0b9f8f2 elementor-section-content-middle elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0b9f8f2\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-78352f0\" data-id=\"78352f0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9f2fe54 elementor-widget elementor-widget-heading\" data-id=\"9f2fe54\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Kontaktieren Sie Ihre Experten f\u00fcr Bauglas<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-901a834 elementor-widget elementor-widget-text-editor\" data-id=\"901a834\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Wir helfen Ihnen, die Fallstricke zu vermeiden und die Qualit\u00e4t und den Wert zu liefern, die Ihr Bauglas braucht &#8211; p\u00fcnktlich und im Rahmen des Budgets.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3be7026 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"3be7026\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg elementor-animation-float\" href=\"https:\/\/hexadindustries.com\/de\/anfrage\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Sofortiges Angebot einholen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-9df4066\" data-id=\"9df4066\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Alle Geb\u00e4ude Glas Gro\u00dfhandel zum Fabrikpreis Sie brauchen mehr als nur ein einziges Glasmaterial, Sie brauchen einen erfahrenen Lieferanten, der seit 12 Jahren in diesem Bereich t\u00e4tig ist, um Ihre Marke aufzubauen und Ihre Gewinne zu steigern; Lassen Sie sich von HEXAD zum gesch\u00e4ftlichen Erfolg verhelfen Sofortiges Angebot einholen All-in-One-L\u00f6sung f\u00fcr Geb\u00e4udeglas Dank der fortschrittlichen [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-2577","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/hexadindustries.com\/de\/wp-json\/wp\/v2\/pages\/2577","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hexadindustries.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/hexadindustries.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/hexadindustries.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hexadindustries.com\/de\/wp-json\/wp\/v2\/comments?post=2577"}],"version-history":[{"count":14,"href":"https:\/\/hexadindustries.com\/de\/wp-json\/wp\/v2\/pages\/2577\/revisions"}],"predecessor-version":[{"id":7349,"href":"https:\/\/hexadindustries.com\/de\/wp-json\/wp\/v2\/pages\/2577\/revisions\/7349"}],"wp:attachment":[{"href":"https:\/\/hexadindustries.com\/de\/wp-json\/wp\/v2\/media?parent=2577"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}